{"id":1062,"date":"2013-06-03T00:56:00","date_gmt":"2013-06-03T07:56:00","guid":{"rendered":"http:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class.jpg"},"modified":"2013-06-03T00:56:00","modified_gmt":"2013-06-03T07:56:00","slug":"for-voice-class","status":"inherit","type":"attachment","link":"https:\/\/pages.palomar.edu\/mmufson\/classes\/for-voice-class\/","title":{"rendered":"For Voice class"},"author":80,"featured_media":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_links_to":"","_links_to_target":""},"class_list":["post-1062","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"259\" height=\"300\" src=\"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class-259x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class-259x300.jpg 259w, https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class.jpg 345w\" sizes=\"auto, (max-width: 259px) 100vw, 259px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":345,"height":399,"file":"2013\/05\/For-Voice-class.jpg","sizes":{"thumbnail":{"file":"For-Voice-class-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class-150x150.jpg"},"medium":{"file":"For-Voice-class-259x300.jpg","width":259,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class-259x300.jpg"},"post-thumbnail":{"file":"For-Voice-class-320x200.jpg","width":320,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class-320x200.jpg"},"full":{"file":"For-Voice-class.jpg","width":345,"height":399,"mime_type":"image\/jpeg","source_url":"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class.jpg"}},"image_meta":{"aperture":0,"credit":"","camera":"","caption":"","created_timestamp":0,"copyright":"","focal_length":0,"iso":0,"shutter_speed":0,"title":""}},"post":495,"source_url":"https:\/\/pages.palomar.edu\/mmufson\/wp-content\/uploads\/sites\/94\/2013\/05\/For-Voice-class.jpg","_links":{"self":[{"href":"https:\/\/pages.palomar.edu\/mmufson\/wp-json\/wp\/v2\/media\/1062","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pages.palomar.edu\/mmufson\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/pages.palomar.edu\/mmufson\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/pages.palomar.edu\/mmufson\/wp-json\/wp\/v2\/users\/80"}],"replies":[{"embeddable":true,"href":"https:\/\/pages.palomar.edu\/mmufson\/wp-json\/wp\/v2\/comments?post=1062"}],"wp:attached-to":[{"embeddable":true,"post_type":"page","id":495,"href":"https:\/\/pages.palomar.edu\/mmufson\/wp-json\/wp\/v2\/pages\/495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}